{"id":1492,"date":"2013-04-20T20:13:11","date_gmt":"2013-04-20T20:13:11","guid":{"rendered":"http:\/\/lineandbox.com\/?p=1492"},"modified":"2016-08-10T02:42:37","modified_gmt":"2016-08-10T02:42:37","slug":"orchids","status":"publish","type":"post","link":"http:\/\/lineandbox.com\/blog\/uncategorized\/orchids","title":{"rendered":"Orchids"},"content":{"rendered":"<p>Last Sunday we went to the NYC Botanical Garden in the Bronx. It was a perfect day so of course half of New York had the same idea. It was beautiful none the less. The feature was an orchid show! So sexy, those flowers.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-1492 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"145\" src=\"http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-12-150x150.jpg 150w, http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-12-200x200.jpg 200w\" sizes=\"auto, (max-width: 145px) 100vw, 145px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-111-e1366488666255.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"145\" src=\"http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-111-e1366488666255-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-10-e1366488680893.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"145\" src=\"http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-10-e1366488680893-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-91-e1366488694293.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"145\" src=\"http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-91-e1366488694293-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-8-e1366488711919.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"145\" height=\"145\" src=\"http:\/\/lineandbox.com\/blog\/wp-content\/uploads\/2013\/04\/photo-8-e1366488711919-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Last Sunday we went to the NYC Botanical Garden in the Bronx. It was a perfect day so of course half of New York had the same idea. It was beautiful none the less. The feature was an orchid show! &hellip; <a href=\"http:\/\/lineandbox.com\/blog\/uncategorized\/orchids\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,12,1],"tags":[],"class_list":["post-1492","post","type-post","status-publish","format-standard","hentry","category-america","category-day","category-uncategorized"],"_links":{"self":[{"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/posts\/1492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/comments?post=1492"}],"version-history":[{"count":4,"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/posts\/1492\/revisions"}],"predecessor-version":[{"id":1644,"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/posts\/1492\/revisions\/1644"}],"wp:attachment":[{"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/media?parent=1492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/categories?post=1492"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lineandbox.com\/blog\/wp-json\/wp\/v2\/tags?post=1492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}